﻿{"id":2999,"date":"2016-12-08T22:03:21","date_gmt":"2016-12-08T21:03:21","guid":{"rendered":"https:\/\/dahoo.fr\/wordpress\/?p=2999"},"modified":"2016-12-10T11:42:06","modified_gmt":"2016-12-10T10:42:06","slug":"wamp-mysqldump","status":"publish","type":"post","link":"https:\/\/dahoo.fr\/wordpress\/wamp-mysqldump\/","title":{"rendered":"Mysqldump : dump rapide et efficace"},"content":{"rendered":"<p>Une petite solution simple pour effectuer des backups de votre base de donn\u00e9es.<\/p>\n<p><!--more--><\/p>\n<h3>Windows \u00a0: mysqdump et le path<\/h3>\n<p style=\"text-align: justify;\">Pour windows, pour que mysqldump soit reconnu dans le prompte, vous devez l&rsquo;ajouter dans les variables d\u2019environnement. Pour cela, \u00e9diter le path du syst\u00e8me et ajouter le chemin vers le bin de mysql\u00a0pour ma part le chemin est <strong>\u00ab\u00a0C:\\wamp64\\bin\\mysql\\mysql5.7.14\\bin\\\u00a0\u00bb<\/strong><\/p>\n<p style=\"text-align: justify;\"><a href=\"https:\/\/dahoo.fr\/wordpress\/wp-content\/uploads\/2016\/11\/path-mysqldump.png\"><img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-full wp-image-3000\" src=\"https:\/\/dahoo.fr\/wordpress\/wp-content\/uploads\/2016\/11\/path-mysqldump.png\" alt=\"path-mysqldump\" width=\"590\" height=\"800\" srcset=\"https:\/\/dahoo.fr\/wordpress\/wp-content\/uploads\/2016\/11\/path-mysqldump.png 590w, https:\/\/dahoo.fr\/wordpress\/wp-content\/uploads\/2016\/11\/path-mysqldump-221x300.png 221w\" sizes=\"auto, (max-width: 590px) 100vw, 590px\" \/><\/a><\/p>\n<p>&nbsp;<\/p>\n<h3>Le dump de la base<\/h3>\n<p>Ex\u00e9cuter dans le cmd la commande suivante :<\/p>\n<ul>\n<li>HOST =&gt; localhost<\/li>\n<li>USER =&gt; login de la base<\/li>\n<li>PASSWORD =&gt; mot de passe de la base<\/li>\n<li>DATABASE \u00a0 =&gt; nom de la base<\/li>\n<li>TABLE =&gt; Nom des tables \u00e0 sauvegarder &#8211; Optionnel<\/li>\n<li>DESTINATION =&gt;\u00a0R\u00e9pertoire + nom o\u00f9 sauvegarder le dump de la base de donn\u00e9es<\/li>\n<\/ul>\n<blockquote><p>mysqldump &#8211;host=HOST &#8211;user=USER &#8211;password=PASSWORD DATABASE TABLE &gt;\u00a0DESTINATION<\/p><\/blockquote>\n<p>&nbsp;<\/p>\n<p>En cadeau, la fonction pour PHP \ud83d\ude09<\/p>\n<blockquote><p>&lt;?php<br \/>\n$host = &lsquo;localhost&rsquo;;<br \/>\n$username = &lsquo;root&rsquo;;<br \/>\n$password = &lsquo;mon_mot_de_passe&rsquo;;<br \/>\n$db = &lsquo;nom_de_ma_base_de_donn\u00e9es&rsquo;;<br \/>\n$table = &lsquo;table1 table2&rsquo;; \/\/Nom des tables \u00e0 sauvegarder &#8211; Optionnel<br \/>\n$rep = &lsquo;.\/rep\/&rsquo;; \/\/R\u00e9pertoire o\u00f9 sauvegarder le dump de la base de donn\u00e9es<\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p>system(\u00ab\u00a0mysqldump &#8211;host=\u00a0\u00bb.$host.\u00a0\u00bb &#8211;user=\u00a0\u00bb.$username.\u00a0\u00bb &#8212; password=\u00a0\u00bb.$password.\u00a0\u00bb\u00a0\u00bb.$db.\u00a0\u00bb \u00ab\u00a0.$table.\u00a0\u00bb &gt; \u00ab\u00a0.$rep.$db.\u00a0\u00bb-\u00ab\u00a0.date(\u00ab\u00a0d-m-Y-H\\hi\u00a0\u00bb).\u00a0\u00bb.sql\u00a0\u00bb);<\/p><\/blockquote>\n","protected":false},"excerpt":{"rendered":"<p>Une petite solution simple pour effectuer des backups de votre base de donn\u00e9es.<\/p>\n","protected":false},"author":1,"featured_media":3033,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[23,96,50,7],"tags":[332,331,328,329,330,64],"class_list":["post-2999","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-linux","category-outils","category-snippet","category-windows","tag-backup","tag-envirronement","tag-mysqldump","tag-path","tag-varaible","tag-windows-2"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.4 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Mysqldump : dump rapide et efficace - D@hoo<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/dahoo.fr\/wordpress\/wamp-mysqldump\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Mysqldump : dump rapide et efficace - D@hoo\" \/>\n<meta property=\"og:description\" content=\"Une petite solution simple pour effectuer des backups de votre base de donn\u00e9es.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/dahoo.fr\/wordpress\/wamp-mysqldump\/\" \/>\n<meta property=\"og:site_name\" content=\"D@hoo\" \/>\n<meta property=\"article:published_time\" content=\"2016-12-08T21:03:21+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2016-12-10T10:42:06+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/dahoo.fr\/wordpress\/wp-content\/uploads\/2016\/12\/SQL-logo.png\" \/>\n\t<meta property=\"og:image:width\" content=\"620\" \/>\n\t<meta property=\"og:image:height\" content=\"210\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"author\" content=\"Fabacks\" \/>\n<meta name=\"twitter:label1\" content=\"\u00c9crit par\" \/>\n\t<meta name=\"twitter:data1\" content=\"Fabacks\" \/>\n\t<meta name=\"twitter:label2\" content=\"Dur\u00e9e de lecture estim\u00e9e\" \/>\n\t<meta name=\"twitter:data2\" content=\"1 minute\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/dahoo.fr\\\/wordpress\\\/wamp-mysqldump\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/dahoo.fr\\\/wordpress\\\/wamp-mysqldump\\\/\"},\"author\":{\"name\":\"Fabacks\",\"@id\":\"https:\\\/\\\/dahoo.fr\\\/wordpress\\\/#\\\/schema\\\/person\\\/08ab6e7b6f186b7e033fe862d72137d2\"},\"headline\":\"Mysqldump : dump rapide et efficace\",\"datePublished\":\"2016-12-08T21:03:21+00:00\",\"dateModified\":\"2016-12-10T10:42:06+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/dahoo.fr\\\/wordpress\\\/wamp-mysqldump\\\/\"},\"wordCount\":213,\"commentCount\":0,\"image\":{\"@id\":\"https:\\\/\\\/dahoo.fr\\\/wordpress\\\/wamp-mysqldump\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/dahoo.fr\\\/wordpress\\\/wp-content\\\/uploads\\\/2016\\\/12\\\/SQL-logo.png\",\"keywords\":[\"backup\",\"envirronement\",\"mysqldump\",\"path\",\"varaible\",\"windows\"],\"articleSection\":[\"Linux\",\"Outils\",\"Snippet\",\"Windows\"],\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/dahoo.fr\\\/wordpress\\\/wamp-mysqldump\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/dahoo.fr\\\/wordpress\\\/wamp-mysqldump\\\/\",\"url\":\"https:\\\/\\\/dahoo.fr\\\/wordpress\\\/wamp-mysqldump\\\/\",\"name\":\"Mysqldump : dump rapide et efficace - D@hoo\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/dahoo.fr\\\/wordpress\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/dahoo.fr\\\/wordpress\\\/wamp-mysqldump\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/dahoo.fr\\\/wordpress\\\/wamp-mysqldump\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/dahoo.fr\\\/wordpress\\\/wp-content\\\/uploads\\\/2016\\\/12\\\/SQL-logo.png\",\"datePublished\":\"2016-12-08T21:03:21+00:00\",\"dateModified\":\"2016-12-10T10:42:06+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/dahoo.fr\\\/wordpress\\\/#\\\/schema\\\/person\\\/08ab6e7b6f186b7e033fe862d72137d2\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/dahoo.fr\\\/wordpress\\\/wamp-mysqldump\\\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/dahoo.fr\\\/wordpress\\\/wamp-mysqldump\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/dahoo.fr\\\/wordpress\\\/wamp-mysqldump\\\/#primaryimage\",\"url\":\"https:\\\/\\\/dahoo.fr\\\/wordpress\\\/wp-content\\\/uploads\\\/2016\\\/12\\\/SQL-logo.png\",\"contentUrl\":\"https:\\\/\\\/dahoo.fr\\\/wordpress\\\/wp-content\\\/uploads\\\/2016\\\/12\\\/SQL-logo.png\",\"width\":620,\"height\":210},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/dahoo.fr\\\/wordpress\\\/wamp-mysqldump\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Accueil\",\"item\":\"https:\\\/\\\/dahoo.fr\\\/wordpress\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Mysqldump : dump rapide et efficace\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/dahoo.fr\\\/wordpress\\\/#website\",\"url\":\"https:\\\/\\\/dahoo.fr\\\/wordpress\\\/\",\"name\":\"D@hoo\",\"description\":\"La taverne du geek\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/dahoo.fr\\\/wordpress\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/dahoo.fr\\\/wordpress\\\/#\\\/schema\\\/person\\\/08ab6e7b6f186b7e033fe862d72137d2\",\"name\":\"Fabacks\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/5774810a4a71ec90d75c578017954d3e8d660747be025fdae4d44599410b4806?s=96&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/5774810a4a71ec90d75c578017954d3e8d660747be025fdae4d44599410b4806?s=96&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/5774810a4a71ec90d75c578017954d3e8d660747be025fdae4d44599410b4806?s=96&r=g\",\"caption\":\"Fabacks\"},\"description\":\"Fabacks, fondateur du projet Dahoo proposant des news, des tutos, des tests tout cela gratuitement. Un bidouilleur et fan d'informatique en tout genre qui vous fera partager ses exp\u00e9riences.\",\"sameAs\":[\"https:\\\/\\\/dahoo.fr\"],\"url\":\"https:\\\/\\\/dahoo.fr\\\/wordpress\\\/author\\\/fabien\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Mysqldump : dump rapide et efficace - D@hoo","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/dahoo.fr\/wordpress\/wamp-mysqldump\/","og_locale":"fr_FR","og_type":"article","og_title":"Mysqldump : dump rapide et efficace - D@hoo","og_description":"Une petite solution simple pour effectuer des backups de votre base de donn\u00e9es.","og_url":"https:\/\/dahoo.fr\/wordpress\/wamp-mysqldump\/","og_site_name":"D@hoo","article_published_time":"2016-12-08T21:03:21+00:00","article_modified_time":"2016-12-10T10:42:06+00:00","og_image":[{"width":620,"height":210,"url":"https:\/\/dahoo.fr\/wordpress\/wp-content\/uploads\/2016\/12\/SQL-logo.png","type":"image\/png"}],"author":"Fabacks","twitter_misc":{"\u00c9crit par":"Fabacks","Dur\u00e9e de lecture estim\u00e9e":"1 minute"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/dahoo.fr\/wordpress\/wamp-mysqldump\/#article","isPartOf":{"@id":"https:\/\/dahoo.fr\/wordpress\/wamp-mysqldump\/"},"author":{"name":"Fabacks","@id":"https:\/\/dahoo.fr\/wordpress\/#\/schema\/person\/08ab6e7b6f186b7e033fe862d72137d2"},"headline":"Mysqldump : dump rapide et efficace","datePublished":"2016-12-08T21:03:21+00:00","dateModified":"2016-12-10T10:42:06+00:00","mainEntityOfPage":{"@id":"https:\/\/dahoo.fr\/wordpress\/wamp-mysqldump\/"},"wordCount":213,"commentCount":0,"image":{"@id":"https:\/\/dahoo.fr\/wordpress\/wamp-mysqldump\/#primaryimage"},"thumbnailUrl":"https:\/\/dahoo.fr\/wordpress\/wp-content\/uploads\/2016\/12\/SQL-logo.png","keywords":["backup","envirronement","mysqldump","path","varaible","windows"],"articleSection":["Linux","Outils","Snippet","Windows"],"inLanguage":"fr-FR","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/dahoo.fr\/wordpress\/wamp-mysqldump\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/dahoo.fr\/wordpress\/wamp-mysqldump\/","url":"https:\/\/dahoo.fr\/wordpress\/wamp-mysqldump\/","name":"Mysqldump : dump rapide et efficace - D@hoo","isPartOf":{"@id":"https:\/\/dahoo.fr\/wordpress\/#website"},"primaryImageOfPage":{"@id":"https:\/\/dahoo.fr\/wordpress\/wamp-mysqldump\/#primaryimage"},"image":{"@id":"https:\/\/dahoo.fr\/wordpress\/wamp-mysqldump\/#primaryimage"},"thumbnailUrl":"https:\/\/dahoo.fr\/wordpress\/wp-content\/uploads\/2016\/12\/SQL-logo.png","datePublished":"2016-12-08T21:03:21+00:00","dateModified":"2016-12-10T10:42:06+00:00","author":{"@id":"https:\/\/dahoo.fr\/wordpress\/#\/schema\/person\/08ab6e7b6f186b7e033fe862d72137d2"},"breadcrumb":{"@id":"https:\/\/dahoo.fr\/wordpress\/wamp-mysqldump\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/dahoo.fr\/wordpress\/wamp-mysqldump\/"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/dahoo.fr\/wordpress\/wamp-mysqldump\/#primaryimage","url":"https:\/\/dahoo.fr\/wordpress\/wp-content\/uploads\/2016\/12\/SQL-logo.png","contentUrl":"https:\/\/dahoo.fr\/wordpress\/wp-content\/uploads\/2016\/12\/SQL-logo.png","width":620,"height":210},{"@type":"BreadcrumbList","@id":"https:\/\/dahoo.fr\/wordpress\/wamp-mysqldump\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Accueil","item":"https:\/\/dahoo.fr\/wordpress\/"},{"@type":"ListItem","position":2,"name":"Mysqldump : dump rapide et efficace"}]},{"@type":"WebSite","@id":"https:\/\/dahoo.fr\/wordpress\/#website","url":"https:\/\/dahoo.fr\/wordpress\/","name":"D@hoo","description":"La taverne du geek","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/dahoo.fr\/wordpress\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Person","@id":"https:\/\/dahoo.fr\/wordpress\/#\/schema\/person\/08ab6e7b6f186b7e033fe862d72137d2","name":"Fabacks","image":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/secure.gravatar.com\/avatar\/5774810a4a71ec90d75c578017954d3e8d660747be025fdae4d44599410b4806?s=96&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/5774810a4a71ec90d75c578017954d3e8d660747be025fdae4d44599410b4806?s=96&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/5774810a4a71ec90d75c578017954d3e8d660747be025fdae4d44599410b4806?s=96&r=g","caption":"Fabacks"},"description":"Fabacks, fondateur du projet Dahoo proposant des news, des tutos, des tests tout cela gratuitement. Un bidouilleur et fan d'informatique en tout genre qui vous fera partager ses exp\u00e9riences.","sameAs":["https:\/\/dahoo.fr"],"url":"https:\/\/dahoo.fr\/wordpress\/author\/fabien\/"}]}},"_links":{"self":[{"href":"https:\/\/dahoo.fr\/wordpress\/wp-json\/wp\/v2\/posts\/2999","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/dahoo.fr\/wordpress\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/dahoo.fr\/wordpress\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/dahoo.fr\/wordpress\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/dahoo.fr\/wordpress\/wp-json\/wp\/v2\/comments?post=2999"}],"version-history":[{"count":0,"href":"https:\/\/dahoo.fr\/wordpress\/wp-json\/wp\/v2\/posts\/2999\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/dahoo.fr\/wordpress\/wp-json\/wp\/v2\/media\/3033"}],"wp:attachment":[{"href":"https:\/\/dahoo.fr\/wordpress\/wp-json\/wp\/v2\/media?parent=2999"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/dahoo.fr\/wordpress\/wp-json\/wp\/v2\/categories?post=2999"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/dahoo.fr\/wordpress\/wp-json\/wp\/v2\/tags?post=2999"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}